{"id":12373,"date":"2022-04-26T16:13:06","date_gmt":"2022-04-26T14:13:06","guid":{"rendered":"http:\/\/vps-565ece63.vps.ovh.net\/?post_type=agences&#038;p=12373"},"modified":"2024-04-09T10:19:46","modified_gmt":"2024-04-09T08:19:46","slug":"saint-etienne","status":"publish","type":"agences","link":"https:\/\/mediaco-groupe.com\/en\/agences\/saint-etienne\/","title":{"rendered":"Saint Etienne"},"content":{"rendered":"<p><strong>Mediaco Loire \u00e0 Saint-\u00c9tienne <\/strong>est une entreprise sp\u00e9cialis\u00e9e dans la location de mat\u00e9riels de levage (de grues, de grues mobiles, de camion bras, de nacelles, de double treuils, de treuils), manutention et transport.<\/p>\n<p>Bas\u00e9e dans la Loire, la soci\u00e9t\u00e9 intervient \u00e9galement dans les transferts industriels. <strong>L\u2019intervention de nos sp\u00e9cialistes hautement qualifi\u00e9s, conjuguant efficacit\u00e9 et exp\u00e9rience,\u00a0<\/strong>permet d\u2019assurer en prestation \u00e0 toutes vos probl\u00e9matiques sur vos chantiers.\u00a0<b>Le parc d\u2019engins disponible \u00e0 vos besoins de levage, manutention, transport, stockage et logistique : <\/b>grue mobile, grue automotrice, grue \u00e0 tour, camion bras, camion grue, nacelle.<\/p>\n<p>Cette flotte de mat\u00e9riels est \u00e0 votre disposition en location avec nos op\u00e9rateurs exp\u00e9riment\u00e9s, performants, sp\u00e9cialis\u00e9s et form\u00e9s depuis plus de 40 ans. <strong>Mediaco Loire \u00e0 Saint-\u00c9tienne<\/strong>\u00a0est une Agence du Groupe Mediaco, num\u00e9ro 1 en France dans le levage et la manutention. N\u2019h\u00e9sitez pas \u00e0 nous contacter via le\u00a0<strong>formulaire de contact<\/strong> ci-dessus. Votre demande sera trait\u00e9e dans les meilleurs d\u00e9lais.<\/p>","protected":false},"author":1,"featured_media":12375,"template":"","class_list":["post-12373","agences","type-agences","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entreprise de levage \u00e0 Saint Etienne - MEDIACO<\/title>\n<meta name=\"description\" content=\"Agence Mediaco Loire, location et vente d&#039;engin de levage et de manutention : grue mobile, nacelle \u00e9l\u00e9vatrice, camion grue et camion bras.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mediaco-groupe.com\/en\/agences\/saint-etienne\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entreprise de levage \u00e0 Saint Etienne - MEDIACO\" \/>\n<meta property=\"og:description\" content=\"Agence Mediaco Loire, location et vente d&#039;engin de levage et de manutention : grue mobile, nacelle \u00e9l\u00e9vatrice, camion grue et camion bras.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mediaco-groupe.com\/en\/agences\/saint-etienne\/\" \/>\n<meta property=\"og:site_name\" content=\"Location et vente de nacelles, grues, mat\u00e9riels de levage - Mediaco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GroupeMediaco\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-09T08:19:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/04\/grue-mobile-st-etienne.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@GroupeMediaco\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/agences\\\/saint-etienne\\\/\",\"url\":\"https:\\\/\\\/mediaco-groupe.com\\\/agences\\\/saint-etienne\\\/\",\"name\":\"Entreprise de levage \u00e0 Saint Etienne - MEDIACO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/agences\\\/saint-etienne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/agences\\\/saint-etienne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mediaco-groupe.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/grue-mobile-st-etienne.webp\",\"datePublished\":\"2022-04-26T14:13:06+00:00\",\"dateModified\":\"2024-04-09T08:19:46+00:00\",\"description\":\"Agence Mediaco Loire, location et vente d'engin de levage et de manutention : grue mobile, nacelle \u00e9l\u00e9vatrice, camion grue et camion bras.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/agences\\\/saint-etienne\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mediaco-groupe.com\\\/agences\\\/saint-etienne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/agences\\\/saint-etienne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mediaco-groupe.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/grue-mobile-st-etienne.webp\",\"contentUrl\":\"https:\\\/\\\/mediaco-groupe.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/grue-mobile-st-etienne.webp\",\"width\":1920,\"height\":1440,\"caption\":\"camion grue st etienne\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/agences\\\/saint-etienne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agences\",\"item\":\"https:\\\/\\\/mediaco-groupe.com\\\/agences\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Saint Etienne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/\",\"name\":\"Location et vente de nacelles, grues, mat\u00e9riels de levage - Mediaco\",\"description\":\"Premier r\u00e9seau en France dans le Levage et la Manutention\",\"publisher\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#organization\",\"name\":\"Mediaco Levage\",\"url\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mediaco-groupe.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-mediaco.svg\",\"contentUrl\":\"https:\\\/\\\/mediaco-groupe.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-mediaco.svg\",\"width\":590,\"height\":72,\"caption\":\"Mediaco Levage\"},\"image\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GroupeMediaco\",\"https:\\\/\\\/x.com\\\/GroupeMediaco\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mediaco\\\/\",\"https:\\\/\\\/www.youtube.com\\\/MediacoLevage\",\"https:\\\/\\\/www.instagram.com\\\/groupemediaco\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lifting agency in Saint-Etienne - MEDIACO","description":"Mediaco Loire agency, rental and sale of lifting and handling equipment: mobile cranes, aerial work platforms, crane trucks and arm trucks.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mediaco-groupe.com\/en\/agences\/saint-etienne\/","og_locale":"en_GB","og_type":"article","og_title":"Entreprise de levage \u00e0 Saint Etienne - MEDIACO","og_description":"Agence Mediaco Loire, location et vente d'engin de levage et de manutention : grue mobile, nacelle \u00e9l\u00e9vatrice, camion grue et camion bras.","og_url":"https:\/\/mediaco-groupe.com\/en\/agences\/saint-etienne\/","og_site_name":"Location et vente de nacelles, grues, mat\u00e9riels de levage - Mediaco","article_publisher":"https:\/\/www.facebook.com\/GroupeMediaco","article_modified_time":"2024-04-09T08:19:46+00:00","og_image":[{"width":1920,"height":1440,"url":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/04\/grue-mobile-st-etienne.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@GroupeMediaco","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mediaco-groupe.com\/agences\/saint-etienne\/","url":"https:\/\/mediaco-groupe.com\/agences\/saint-etienne\/","name":"Lifting agency in Saint-Etienne - MEDIACO","isPartOf":{"@id":"https:\/\/mediaco-groupe.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mediaco-groupe.com\/agences\/saint-etienne\/#primaryimage"},"image":{"@id":"https:\/\/mediaco-groupe.com\/agences\/saint-etienne\/#primaryimage"},"thumbnailUrl":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/04\/grue-mobile-st-etienne.webp","datePublished":"2022-04-26T14:13:06+00:00","dateModified":"2024-04-09T08:19:46+00:00","description":"Mediaco Loire agency, rental and sale of lifting and handling equipment: mobile cranes, aerial work platforms, crane trucks and arm trucks.","breadcrumb":{"@id":"https:\/\/mediaco-groupe.com\/agences\/saint-etienne\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mediaco-groupe.com\/agences\/saint-etienne\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/mediaco-groupe.com\/agences\/saint-etienne\/#primaryimage","url":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/04\/grue-mobile-st-etienne.webp","contentUrl":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/04\/grue-mobile-st-etienne.webp","width":1920,"height":1440,"caption":"camion grue st etienne"},{"@type":"BreadcrumbList","@id":"https:\/\/mediaco-groupe.com\/agences\/saint-etienne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/mediaco-groupe.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Agences","item":"https:\/\/mediaco-groupe.com\/agences\/"},{"@type":"ListItem","position":3,"name":"Saint Etienne"}]},{"@type":"WebSite","@id":"https:\/\/mediaco-groupe.com\/fr\/#website","url":"https:\/\/mediaco-groupe.com\/fr\/","name":"Location et vente de nacelles, grues, mat\u00e9riels de levage - Mediaco","description":"Premier r\u00e9seau en France dans le Levage et la Manutention","publisher":{"@id":"https:\/\/mediaco-groupe.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mediaco-groupe.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/mediaco-groupe.com\/fr\/#organization","name":"Mediaco Levage","url":"https:\/\/mediaco-groupe.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/mediaco-groupe.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/01\/logo-mediaco.svg","contentUrl":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/01\/logo-mediaco.svg","width":590,"height":72,"caption":"Mediaco Levage"},"image":{"@id":"https:\/\/mediaco-groupe.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GroupeMediaco","https:\/\/x.com\/GroupeMediaco","https:\/\/www.linkedin.com\/company\/mediaco\/","https:\/\/www.youtube.com\/MediacoLevage","https:\/\/www.instagram.com\/groupemediaco\/"]}]}},"_links":{"self":[{"href":"https:\/\/mediaco-groupe.com\/en\/wp-json\/wp\/v2\/agences\/12373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mediaco-groupe.com\/en\/wp-json\/wp\/v2\/agences"}],"about":[{"href":"https:\/\/mediaco-groupe.com\/en\/wp-json\/wp\/v2\/types\/agences"}],"author":[{"embeddable":true,"href":"https:\/\/mediaco-groupe.com\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mediaco-groupe.com\/en\/wp-json\/wp\/v2\/media\/12375"}],"wp:attachment":[{"href":"https:\/\/mediaco-groupe.com\/en\/wp-json\/wp\/v2\/media?parent=12373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}