{"id":12089,"date":"2022-04-22T15:08:10","date_gmt":"2022-04-22T13:08:10","guid":{"rendered":"http:\/\/vps-565ece63.vps.ovh.net\/?post_type=agences&#038;p=12089"},"modified":"2023-04-27T10:28:47","modified_gmt":"2023-04-27T08:28:47","slug":"frejus","status":"publish","type":"agences","link":"https:\/\/mediaco-groupe.com\/fr\/agences\/frejus\/","title":{"rendered":"Fr\u00e9jus"},"content":{"rendered":"<p><strong>Mediaco Centre Var\u00a0<\/strong>(anciennement Chieusse Levage) est une entreprise sp\u00e9cialis\u00e9e dans la location de mat\u00e9riels de levage (de grues, de grues mobiles, de camion bras, de nacelles, de double treuils, de treuils), manutention et transport. Bas\u00e9e dans le Var \u00e0 Fr\u00e9jus, la soci\u00e9t\u00e9 intervient \u00e9galement dans les travaux forestier. <strong>L\u2019intervention de nos sp\u00e9cialistes hautement qualifi\u00e9s, conjuguant efficacit\u00e9 et exp\u00e9rience,\u00a0<\/strong>permet d\u2019assurer\u00a0en prestation \u00e0 toutes vos probl\u00e9matiques sur vos chantiers.<\/p>\n<p><b>Le parc d\u2019engins disponible \u00e0 vos besoins de levage, manutention, transport, stockage et logistique : <\/b>Grue mobile, Grue automotrice, Grue \u00e0 tour, Camion bras, Camion grue et Nacelle.<\/p>\n<p>Cette flotte de mat\u00e9riels est \u00e0 votre disposition en location avec nos op\u00e9rateurs exp\u00e9riment\u00e9s, performants, sp\u00e9cialis\u00e9s et form\u00e9s depuis plus de 40 ans. <strong>Mediaco Centre Var<\/strong> <strong>Fr\u00e9jus<\/strong> est une Agence du Groupe Mediaco, num\u00e9ro 1 en France dans le levage et la manutention. N\u2019h\u00e9sitez pas \u00e0 nous contacter via le <strong>formulaire de contact<\/strong> ci-dessus. Votre demande sera trait\u00e9e dans les meilleurs d\u00e9lais.<\/p>\n","protected":false},"author":1,"featured_media":12097,"template":"","class_list":["post-12089","agences","type-agences","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entreprise de levage et manutention \u00e0 Fr\u00e9jus - MEDIACO<\/title>\n<meta name=\"description\" content=\"Mediaco Centre Var \u00e0 Fr\u00e9jus, location et vente d&#039;engins de levage et de manutention : grue mobile, nacelle, camion grue et camion bras.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mediaco-groupe.com\/fr\/agences\/frejus\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entreprise de levage et manutention \u00e0 Fr\u00e9jus - MEDIACO\" \/>\n<meta property=\"og:description\" content=\"Mediaco Centre Var \u00e0 Fr\u00e9jus, location et vente d&#039;engins de levage et de manutention : grue mobile, nacelle, camion grue et camion bras.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mediaco-groupe.com\/fr\/agences\/frejus\/\" \/>\n<meta property=\"og:site_name\" content=\"Location et vente de nacelles, grues, mat\u00e9riels de levage - Mediaco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GroupeMediaco\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-27T08:28:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/04\/location-grue-frejus.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1479\" \/>\n\t<meta property=\"og:image:height\" content=\"1107\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@GroupeMediaco\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/agences\\\/frejus\\\/\",\"url\":\"https:\\\/\\\/mediaco-groupe.com\\\/agences\\\/frejus\\\/\",\"name\":\"Entreprise de levage et manutention \u00e0 Fr\u00e9jus - MEDIACO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/agences\\\/frejus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/agences\\\/frejus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mediaco-groupe.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/location-grue-frejus.webp\",\"datePublished\":\"2022-04-22T13:08:10+00:00\",\"dateModified\":\"2023-04-27T08:28:47+00:00\",\"description\":\"Mediaco Centre Var \u00e0 Fr\u00e9jus, location et vente d'engins de levage et de manutention : grue mobile, nacelle, camion grue et camion bras.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/agences\\\/frejus\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mediaco-groupe.com\\\/agences\\\/frejus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/agences\\\/frejus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mediaco-groupe.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/location-grue-frejus.webp\",\"contentUrl\":\"https:\\\/\\\/mediaco-groupe.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/location-grue-frejus.webp\",\"width\":1479,\"height\":1107,\"caption\":\"Location grue f\u00e9jus mediaco marseille\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/agences\\\/frejus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agences\",\"item\":\"https:\\\/\\\/mediaco-groupe.com\\\/agences\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fr\u00e9jus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/\",\"name\":\"Location et vente de nacelles, grues, mat\u00e9riels de levage - Mediaco\",\"description\":\"Premier r\u00e9seau en France dans le Levage et la Manutention\",\"publisher\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#organization\",\"name\":\"Mediaco Levage\",\"url\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mediaco-groupe.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-mediaco.svg\",\"contentUrl\":\"https:\\\/\\\/mediaco-groupe.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-mediaco.svg\",\"width\":590,\"height\":72,\"caption\":\"Mediaco Levage\"},\"image\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GroupeMediaco\",\"https:\\\/\\\/x.com\\\/GroupeMediaco\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mediaco\\\/\",\"https:\\\/\\\/www.youtube.com\\\/MediacoLevage\",\"https:\\\/\\\/www.instagram.com\\\/groupemediaco\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entreprise de levage et manutention \u00e0 Fr\u00e9jus - MEDIACO","description":"Mediaco Centre Var \u00e0 Fr\u00e9jus, location et vente d'engins de levage et de manutention : grue mobile, nacelle, camion grue et camion bras.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mediaco-groupe.com\/fr\/agences\/frejus\/","og_locale":"fr_FR","og_type":"article","og_title":"Entreprise de levage et manutention \u00e0 Fr\u00e9jus - MEDIACO","og_description":"Mediaco Centre Var \u00e0 Fr\u00e9jus, location et vente d'engins de levage et de manutention : grue mobile, nacelle, camion grue et camion bras.","og_url":"https:\/\/mediaco-groupe.com\/fr\/agences\/frejus\/","og_site_name":"Location et vente de nacelles, grues, mat\u00e9riels de levage - Mediaco","article_publisher":"https:\/\/www.facebook.com\/GroupeMediaco","article_modified_time":"2023-04-27T08:28:47+00:00","og_image":[{"width":1479,"height":1107,"url":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/04\/location-grue-frejus.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@GroupeMediaco","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mediaco-groupe.com\/agences\/frejus\/","url":"https:\/\/mediaco-groupe.com\/agences\/frejus\/","name":"Entreprise de levage et manutention \u00e0 Fr\u00e9jus - MEDIACO","isPartOf":{"@id":"https:\/\/mediaco-groupe.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mediaco-groupe.com\/agences\/frejus\/#primaryimage"},"image":{"@id":"https:\/\/mediaco-groupe.com\/agences\/frejus\/#primaryimage"},"thumbnailUrl":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/04\/location-grue-frejus.webp","datePublished":"2022-04-22T13:08:10+00:00","dateModified":"2023-04-27T08:28:47+00:00","description":"Mediaco Centre Var \u00e0 Fr\u00e9jus, location et vente d'engins de levage et de manutention : grue mobile, nacelle, camion grue et camion bras.","breadcrumb":{"@id":"https:\/\/mediaco-groupe.com\/agences\/frejus\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mediaco-groupe.com\/agences\/frejus\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mediaco-groupe.com\/agences\/frejus\/#primaryimage","url":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/04\/location-grue-frejus.webp","contentUrl":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/04\/location-grue-frejus.webp","width":1479,"height":1107,"caption":"Location grue f\u00e9jus mediaco marseille"},{"@type":"BreadcrumbList","@id":"https:\/\/mediaco-groupe.com\/agences\/frejus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/mediaco-groupe.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Agences","item":"https:\/\/mediaco-groupe.com\/agences\/"},{"@type":"ListItem","position":3,"name":"Fr\u00e9jus"}]},{"@type":"WebSite","@id":"https:\/\/mediaco-groupe.com\/fr\/#website","url":"https:\/\/mediaco-groupe.com\/fr\/","name":"Location et vente de nacelles, grues, mat\u00e9riels de levage - Mediaco","description":"Premier r\u00e9seau en France dans le Levage et la Manutention","publisher":{"@id":"https:\/\/mediaco-groupe.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mediaco-groupe.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mediaco-groupe.com\/fr\/#organization","name":"Mediaco Levage","url":"https:\/\/mediaco-groupe.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mediaco-groupe.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/01\/logo-mediaco.svg","contentUrl":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/01\/logo-mediaco.svg","width":590,"height":72,"caption":"Mediaco Levage"},"image":{"@id":"https:\/\/mediaco-groupe.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GroupeMediaco","https:\/\/x.com\/GroupeMediaco","https:\/\/www.linkedin.com\/company\/mediaco\/","https:\/\/www.youtube.com\/MediacoLevage","https:\/\/www.instagram.com\/groupemediaco\/"]}]}},"_links":{"self":[{"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/agences\/12089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/agences"}],"about":[{"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/types\/agences"}],"author":[{"embeddable":true,"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/media\/12097"}],"wp:attachment":[{"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/media?parent=12089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}