{"id":12621,"date":"2022-04-29T17:15:33","date_gmt":"2022-04-29T15:15:33","guid":{"rendered":"http:\/\/vps-565ece63.vps.ovh.net\/?post_type=agences&#038;p=12621"},"modified":"2023-04-27T11:06:06","modified_gmt":"2023-04-27T09:06:06","slug":"valence","status":"publish","type":"agences","link":"https:\/\/mediaco-groupe.com\/fr\/agences\/valence\/","title":{"rendered":"Valence"},"content":{"rendered":"<p><strong>Mediaco Valence<\/strong>\u00a0est une entreprise sp\u00e9cialis\u00e9e dans la location de mat\u00e9riels de levage (de grues, de grues mobiles, de camion bras, de nacelles, de double treuils, de treuils), manutention et transport.<\/p>\n<p>Bas\u00e9e en Auvergne-Rh\u00f4ne-Alpes, la soci\u00e9t\u00e9 intervient \u00e9galement dans les travaux de montage de parc pour \u00e9olienne. <strong>L\u2019intervention de nos sp\u00e9cialistes hautement qualifi\u00e9s, conjuguant efficacit\u00e9 et exp\u00e9rience,\u00a0<\/strong>permet d\u2019assurer en prestation \u00e0 toutes vos probl\u00e9matiques sur vos chantiers.\u00a0<b>Le parc d\u2019engins disponible \u00e0 vos besoins de levage, manutention, transport, stockage et logistique : <\/b>grue mobile, grue automotrice, grue \u00e0 tour, camion bras, camion grue et nacelle.<\/p>\n<p>Cette flotte de mat\u00e9riels est \u00e0 votre disposition en location avec nos op\u00e9rateurs exp\u00e9riment\u00e9s, performants, sp\u00e9cialis\u00e9s et form\u00e9s depuis plus de 40 ans. <strong>Mediaco Valence<\/strong>\u00a0est une Agence du Groupe Mediaco, num\u00e9ro 1 en France dans le levage et la manutention. N\u2019h\u00e9sitez pas \u00e0 nous contacter via le\u00a0<strong>formulaire de contact<\/strong> ci-dessus. Votre demande sera trait\u00e9e dans les meilleurs d\u00e9lais.<\/p>\n","protected":false},"author":1,"featured_media":12623,"template":"","class_list":["post-12621","agences","type-agences","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entreprise de levage et manutention \u00e0 Valence - MEDIACO<\/title>\n<meta name=\"description\" content=\"Agence Valence Levage, location et vente d&#039;engin de levage et de manutention : grue mobile, nacelle \u00e9l\u00e9vatrice, camion grue et camion bras.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mediaco-groupe.com\/fr\/agences\/valence\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entreprise de levage et manutention \u00e0 Valence - MEDIACO\" \/>\n<meta property=\"og:description\" content=\"Agence Valence Levage, location et vente d&#039;engin de levage et de manutention : grue mobile, nacelle \u00e9l\u00e9vatrice, camion grue et camion bras.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mediaco-groupe.com\/fr\/agences\/valence\/\" \/>\n<meta property=\"og:site_name\" content=\"Location et vente de nacelles, grues, mat\u00e9riels de levage - Mediaco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GroupeMediaco\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-27T09:06:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/04\/levage-valence.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1439\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@GroupeMediaco\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/agences\\\/valence\\\/\",\"url\":\"https:\\\/\\\/mediaco-groupe.com\\\/agences\\\/valence\\\/\",\"name\":\"Entreprise de levage et manutention \u00e0 Valence - MEDIACO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/agences\\\/valence\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/agences\\\/valence\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mediaco-groupe.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/levage-valence.webp\",\"datePublished\":\"2022-04-29T15:15:33+00:00\",\"dateModified\":\"2023-04-27T09:06:06+00:00\",\"description\":\"Agence Valence Levage, location et vente d'engin de levage et de manutention : grue mobile, nacelle \u00e9l\u00e9vatrice, camion grue et camion bras.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/agences\\\/valence\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mediaco-groupe.com\\\/agences\\\/valence\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/agences\\\/valence\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mediaco-groupe.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/levage-valence.webp\",\"contentUrl\":\"https:\\\/\\\/mediaco-groupe.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/levage-valence.webp\",\"width\":1920,\"height\":1439,\"caption\":\"op\u00e9ration de levage \u00e0 valence\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/agences\\\/valence\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agences\",\"item\":\"https:\\\/\\\/mediaco-groupe.com\\\/agences\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Valence\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/\",\"name\":\"Location et vente de nacelles, grues, mat\u00e9riels de levage - Mediaco\",\"description\":\"Premier r\u00e9seau en France dans le Levage et la Manutention\",\"publisher\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#organization\",\"name\":\"Mediaco Levage\",\"url\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mediaco-groupe.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-mediaco.svg\",\"contentUrl\":\"https:\\\/\\\/mediaco-groupe.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-mediaco.svg\",\"width\":590,\"height\":72,\"caption\":\"Mediaco Levage\"},\"image\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GroupeMediaco\",\"https:\\\/\\\/x.com\\\/GroupeMediaco\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mediaco\\\/\",\"https:\\\/\\\/www.youtube.com\\\/MediacoLevage\",\"https:\\\/\\\/www.instagram.com\\\/groupemediaco\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entreprise de levage et manutention \u00e0 Valence - MEDIACO","description":"Agence Valence Levage, location et vente d'engin de levage et de manutention : grue mobile, nacelle \u00e9l\u00e9vatrice, camion grue et camion bras.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mediaco-groupe.com\/fr\/agences\/valence\/","og_locale":"fr_FR","og_type":"article","og_title":"Entreprise de levage et manutention \u00e0 Valence - MEDIACO","og_description":"Agence Valence Levage, location et vente d'engin de levage et de manutention : grue mobile, nacelle \u00e9l\u00e9vatrice, camion grue et camion bras.","og_url":"https:\/\/mediaco-groupe.com\/fr\/agences\/valence\/","og_site_name":"Location et vente de nacelles, grues, mat\u00e9riels de levage - Mediaco","article_publisher":"https:\/\/www.facebook.com\/GroupeMediaco","article_modified_time":"2023-04-27T09:06:06+00:00","og_image":[{"width":1920,"height":1439,"url":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/04\/levage-valence.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@GroupeMediaco","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mediaco-groupe.com\/agences\/valence\/","url":"https:\/\/mediaco-groupe.com\/agences\/valence\/","name":"Entreprise de levage et manutention \u00e0 Valence - MEDIACO","isPartOf":{"@id":"https:\/\/mediaco-groupe.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mediaco-groupe.com\/agences\/valence\/#primaryimage"},"image":{"@id":"https:\/\/mediaco-groupe.com\/agences\/valence\/#primaryimage"},"thumbnailUrl":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/04\/levage-valence.webp","datePublished":"2022-04-29T15:15:33+00:00","dateModified":"2023-04-27T09:06:06+00:00","description":"Agence Valence Levage, location et vente d'engin de levage et de manutention : grue mobile, nacelle \u00e9l\u00e9vatrice, camion grue et camion bras.","breadcrumb":{"@id":"https:\/\/mediaco-groupe.com\/agences\/valence\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mediaco-groupe.com\/agences\/valence\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mediaco-groupe.com\/agences\/valence\/#primaryimage","url":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/04\/levage-valence.webp","contentUrl":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/04\/levage-valence.webp","width":1920,"height":1439,"caption":"op\u00e9ration de levage \u00e0 valence"},{"@type":"BreadcrumbList","@id":"https:\/\/mediaco-groupe.com\/agences\/valence\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/mediaco-groupe.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Agences","item":"https:\/\/mediaco-groupe.com\/agences\/"},{"@type":"ListItem","position":3,"name":"Valence"}]},{"@type":"WebSite","@id":"https:\/\/mediaco-groupe.com\/fr\/#website","url":"https:\/\/mediaco-groupe.com\/fr\/","name":"Location et vente de nacelles, grues, mat\u00e9riels de levage - Mediaco","description":"Premier r\u00e9seau en France dans le Levage et la Manutention","publisher":{"@id":"https:\/\/mediaco-groupe.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mediaco-groupe.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mediaco-groupe.com\/fr\/#organization","name":"Mediaco Levage","url":"https:\/\/mediaco-groupe.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mediaco-groupe.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/01\/logo-mediaco.svg","contentUrl":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/01\/logo-mediaco.svg","width":590,"height":72,"caption":"Mediaco Levage"},"image":{"@id":"https:\/\/mediaco-groupe.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GroupeMediaco","https:\/\/x.com\/GroupeMediaco","https:\/\/www.linkedin.com\/company\/mediaco\/","https:\/\/www.youtube.com\/MediacoLevage","https:\/\/www.instagram.com\/groupemediaco\/"]}]}},"_links":{"self":[{"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/agences\/12621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/agences"}],"about":[{"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/types\/agences"}],"author":[{"embeddable":true,"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/media\/12623"}],"wp:attachment":[{"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/media?parent=12621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}