{"id":15,"date":"2022-01-11T10:27:47","date_gmt":"2022-01-11T09:27:47","guid":{"rendered":"http:\/\/vps-565ece63.vps.ovh.net\/?page_id=15"},"modified":"2024-10-30T11:30:00","modified_gmt":"2024-10-30T10:30:00","slug":"actualites-levage","status":"publish","type":"page","link":"https:\/\/mediaco-groupe.com\/fr\/actualites-levage\/","title":{"rendered":"Actualit\u00e9s"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"15\" class=\"elementor elementor-15\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d08c5f3 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"d08c5f3\" data-element_type=\"section\" data-e-type=\"section\" id=\"top\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2795bc18\" data-id=\"2795bc18\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-163ec235 animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"163ec235\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;,&quot;_animation_mobile&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">ACTUALIT\u00c9S MEDIACO LEVAGE<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3473ab8 animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3473ab8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_mobile&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">D\u00e9couvrez quelques-unes de nos plus belles r\u00e9alisations et suivez l'actualit\u00e9 du groupe<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7f56655 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"7f56655\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-641078a\" data-id=\"641078a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ddaef2 elementor-widget__width-auto elementor-hidden-tablet elementor-hidden-mobile animated-fast elementor-invisible elementor-widget elementor-widget-html\" data-id=\"8ddaef2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"triangle-plein\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aff5128 elementor-widget__width-auto animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"aff5128\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;,&quot;_animation_mobile&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">VIE DU GROUPE.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc52a73 animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"bc52a73\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_mobile&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Toujours pr\u00e9sents sur des chantiers en France et \u00e0 l&rsquo;\u00e9tranger, d\u00e9couvrez nos interventions \u00e0 travers nos <strong>95<\/strong><strong>\u00a0agences de proximit\u00e9 dans les domaines du levage, manutention, transport, logistique et stockage.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-04d8908 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"04d8908\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4173377\" data-id=\"4173377\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4bf5a01 animated-fast elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-posts__hover-gradient elementor-invisible elementor-widget elementor-widget-posts\" data-id=\"4bf5a01\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_mobile&quot;:&quot;none&quot;,&quot;cards_columns&quot;:&quot;3&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1242391 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/mediaco-groupe.com\/fr\/mediaco-ca-503-millions-2025\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"293\" src=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/chiffre-affaire-mediaco-300x293.webp\" class=\"attachment-medium size-medium wp-image-1242597\" alt=\"\" srcset=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/chiffre-affaire-mediaco-300x293.webp 300w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/chiffre-affaire-mediaco-1024x999.webp 1024w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/chiffre-affaire-mediaco-768x749.webp 768w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/chiffre-affaire-mediaco-1536x1498.webp 1536w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/chiffre-affaire-mediaco-2048x1997.webp 2048w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/chiffre-affaire-mediaco-12x12.webp 12w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">\u00c9v\u00e8nement<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/mediaco-groupe.com\/fr\/mediaco-ca-503-millions-2025\/\" >\n\t\t\t\tLe groupe Mediaco franchit le cap des 500 M\u20ac en 2025\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t27 avril 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1226391 post type-post status-publish format-standard has-post-thumbnail hentry category-levage\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/mediaco-groupe.com\/fr\/levage-deplacement-avion-centre-val-de-loire\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/levage-avion-chateauroux-300x225.webp\" class=\"attachment-medium size-medium wp-image-1226392\" alt=\"\" srcset=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/levage-avion-chateauroux-300x225.webp 300w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/levage-avion-chateauroux-1024x768.webp 1024w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/levage-avion-chateauroux-768x576.webp 768w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/levage-avion-chateauroux-1536x1152.webp 1536w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/levage-avion-chateauroux-2048x1536.webp 2048w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/levage-avion-chateauroux-16x12.webp 16w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Levage<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/mediaco-groupe.com\/fr\/levage-deplacement-avion-centre-val-de-loire\/\" >\n\t\t\t\tLevage et d\u00e9placement d\u2019un avion de 54 tonnes en Centre-Val de Loire\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t16 mars 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1200092 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/mediaco-groupe.com\/fr\/mediaco-auvergne-installation-nouvelle-agence\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"146\" src=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/mediaco-clermont-nouveau-depot-300x146.webp\" class=\"attachment-medium size-medium wp-image-1200097\" alt=\"\" srcset=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/mediaco-clermont-nouveau-depot-300x146.webp 300w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/mediaco-clermont-nouveau-depot-1024x499.webp 1024w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/mediaco-clermont-nouveau-depot-768x374.webp 768w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/mediaco-clermont-nouveau-depot-1536x749.webp 1536w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/mediaco-clermont-nouveau-depot-18x9.webp 18w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/mediaco-clermont-nouveau-depot.webp 1549w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">\u00c9v\u00e8nement<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/mediaco-groupe.com\/fr\/mediaco-auvergne-installation-nouvelle-agence\/\" >\n\t\t\t\tL\u2019agence MEDIACO Auvergne de Clermont-Ferrand s\u2019installe dans un nouveau d\u00e9p\u00f4t\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t28 janvier 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1112536 post type-post status-publish format-standard has-post-thumbnail hentry category-spmt\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/mediaco-groupe.com\/fr\/chantier-grand-paris-express\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/grand-paris-express-spmt-300x225.webp\" class=\"attachment-medium size-medium wp-image-1112540\" alt=\"Remorque SPMT sur le chantier du Grand Paris Express \u00e0 Nanterre\" srcset=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/grand-paris-express-spmt-300x225.webp 300w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/grand-paris-express-spmt-1024x768.webp 1024w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/grand-paris-express-spmt-768x576.webp 768w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/grand-paris-express-spmt-1536x1152.webp 1536w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/grand-paris-express-spmt-16x12.webp 16w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/grand-paris-express-spmt.webp 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">SPMT<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/mediaco-groupe.com\/fr\/chantier-grand-paris-express\/\" >\n\t\t\t\tMediaco sur le chantier du Grand Paris Express\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t17 novembre 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1112430 post type-post status-publish format-standard has-post-thumbnail hentry category-levage\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/mediaco-groupe.com\/fr\/remise-en-place-du-pont-v-port-havre\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/levage-port-du-havre-pont-300x169.webp\" class=\"attachment-medium size-medium wp-image-1112432\" alt=\"levage au port du havre\" srcset=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/levage-port-du-havre-pont-300x169.webp 300w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/levage-port-du-havre-pont-1024x576.webp 1024w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/levage-port-du-havre-pont-768x432.webp 768w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/levage-port-du-havre-pont-1536x864.webp 1536w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/levage-port-du-havre-pont-18x10.webp 18w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/levage-port-du-havre-pont.webp 1958w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Levage<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/mediaco-groupe.com\/fr\/remise-en-place-du-pont-v-port-havre\/\" >\n\t\t\t\tRemise en place du Pont V au port du Havre\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t16 octobre 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1067702 post type-post status-publish format-standard has-post-thumbnail hentry category-rachat\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/mediaco-groupe.com\/fr\/levouest-rejoint-mediaco\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/levouest-rejoint-le-groupe-300x225.webp\" class=\"attachment-medium size-medium wp-image-1067706\" alt=\"\" srcset=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/levouest-rejoint-le-groupe-300x225.webp 300w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/levouest-rejoint-le-groupe-1024x768.webp 1024w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/levouest-rejoint-le-groupe-768x576.webp 768w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/levouest-rejoint-le-groupe-16x12.webp 16w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/levouest-rejoint-le-groupe.webp 1536w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Rachat<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/mediaco-groupe.com\/fr\/levouest-rejoint-mediaco\/\" >\n\t\t\t\tLevouest rejoint le Groupe Mediaco\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t15 septembre 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1024251 post type-post status-publish format-standard has-post-thumbnail hentry category-levage\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/mediaco-groupe.com\/fr\/levage-synchronise-port-commerce-rochelle-mediaco-poitou-charentes\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/levage-synchronise-port-commerce-la-rochelle-mediaco-300x200.webp\" class=\"attachment-medium size-medium wp-image-1024252\" alt=\"Levage synchronis\u00e9 au Port de Commerce de La Rochelle par Mediaco Poitou-Charentes\" srcset=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/levage-synchronise-port-commerce-la-rochelle-mediaco-300x200.webp 300w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/levage-synchronise-port-commerce-la-rochelle-mediaco-1024x683.webp 1024w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/levage-synchronise-port-commerce-la-rochelle-mediaco-768x512.webp 768w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/levage-synchronise-port-commerce-la-rochelle-mediaco-1536x1024.webp 1536w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/levage-synchronise-port-commerce-la-rochelle-mediaco-18x12.webp 18w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/levage-synchronise-port-commerce-la-rochelle-mediaco.webp 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Levage<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/mediaco-groupe.com\/fr\/levage-synchronise-port-commerce-rochelle-mediaco-poitou-charentes\/\" >\n\t\t\t\tLevage synchronis\u00e9 au Port de Commerce de La Rochelle\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t28 juillet 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1024244 post type-post status-publish format-standard has-post-thumbnail hentry category-levage\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/mediaco-groupe.com\/fr\/chantier-saint-mandrier-sur-mer-mediaco-var\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/chantier-saint-mandrier-sur-mer-mediaco-var-300x225.webp\" class=\"attachment-medium size-medium wp-image-1024248\" alt=\"Chantier \u00e0 Saint-Mandrier-sur-mer par Mediaco Var\" srcset=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/chantier-saint-mandrier-sur-mer-mediaco-var-300x225.webp 300w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/chantier-saint-mandrier-sur-mer-mediaco-var-1024x768.webp 1024w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/chantier-saint-mandrier-sur-mer-mediaco-var-768x576.webp 768w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/chantier-saint-mandrier-sur-mer-mediaco-var-1536x1152.webp 1536w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/chantier-saint-mandrier-sur-mer-mediaco-var-16x12.webp 16w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/chantier-saint-mandrier-sur-mer-mediaco-var.webp 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Levage<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/mediaco-groupe.com\/fr\/chantier-saint-mandrier-sur-mer-mediaco-var\/\" >\n\t\t\t\tDouble intervention \u00e0 Saint-Mandrier-sur-Mer &#8211; Mediaco Var\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t10 juillet 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1024254 post type-post status-publish format-standard has-post-thumbnail hentry category-nacelle\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/mediaco-groupe.com\/fr\/radome-pleumeur-bodou-mediaco-highlift\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"201\" src=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/mediaco-highlift-dome-pleumeur-bodou-300x201.webp\" class=\"attachment-medium size-medium wp-image-1024257\" alt=\"Intervention hors-normes \u00e0 Pleumeur-Bodou (22) pour Mediaco Highlift\" srcset=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/mediaco-highlift-dome-pleumeur-bodou-300x201.webp 300w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/mediaco-highlift-dome-pleumeur-bodou-1024x685.webp 1024w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/mediaco-highlift-dome-pleumeur-bodou-768x514.webp 768w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/mediaco-highlift-dome-pleumeur-bodou-1536x1027.webp 1536w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/mediaco-highlift-dome-pleumeur-bodou-2048x1370.webp 2048w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/mediaco-highlift-dome-pleumeur-bodou-18x12.webp 18w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Nacelle<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/mediaco-groupe.com\/fr\/radome-pleumeur-bodou-mediaco-highlift\/\" >\n\t\t\t\tMediaco Highlift redonne des couleurs au rad\u00f4me de Pleumeur-Bodou\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t26 juin 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>ACTUALIT\u00c9S MEDIACO LEVAGE D\u00e9couvrez quelques-unes de nos plus belles r\u00e9alisations et suivez l&rsquo;actualit\u00e9 du groupe VIE DU GROUPE. Toujours pr\u00e9sents sur des chantiers en France<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-15","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Actualit\u00e9s et Vie du Groupe - MEDIACO<\/title>\n<meta name=\"description\" content=\"Retrouvez toutes les actualit\u00e9s du groupe MEDIACO Levage et suivez nos interventions de levage, manutention, transport et logistique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mediaco-groupe.com\/fr\/actualites-levage\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Actualit\u00e9s et Vie du Groupe - MEDIACO\" \/>\n<meta property=\"og:description\" content=\"Retrouvez toutes les actualit\u00e9s du groupe MEDIACO Levage et suivez nos interventions de levage, manutention, transport et logistique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mediaco-groupe.com\/fr\/actualites-levage\/\" \/>\n<meta property=\"og:site_name\" content=\"Location et vente de nacelles, grues, mat\u00e9riels de levage - Mediaco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GroupeMediaco\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-30T10:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/07\/grue-mobile-industriel-1024x683.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@GroupeMediaco\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/actualites-levage\\\/\",\"url\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/actualites-levage\\\/\",\"name\":\"Actualit\u00e9s et Vie du Groupe - MEDIACO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/actualites-levage\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/actualites-levage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mediaco-groupe.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/grue-mobile-industriel-1024x683.webp\",\"datePublished\":\"2022-01-11T09:27:47+00:00\",\"dateModified\":\"2024-10-30T10:30:00+00:00\",\"description\":\"Retrouvez toutes les actualit\u00e9s du groupe MEDIACO Levage et suivez nos interventions de levage, manutention, transport et logistique.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/actualites-levage\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/actualites-levage\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/actualites-levage\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mediaco-groupe.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/grue-mobile-industriel-1024x683.webp\",\"contentUrl\":\"https:\\\/\\\/mediaco-groupe.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/grue-mobile-industriel-1024x683.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/actualites-levage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualit\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/\",\"name\":\"Location et vente de nacelles, grues, mat\u00e9riels de levage - Mediaco\",\"description\":\"Premier r\u00e9seau en France dans le Levage et la Manutention\",\"publisher\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#organization\",\"name\":\"Mediaco Levage\",\"url\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mediaco-groupe.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-mediaco.svg\",\"contentUrl\":\"https:\\\/\\\/mediaco-groupe.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-mediaco.svg\",\"width\":590,\"height\":72,\"caption\":\"Mediaco Levage\"},\"image\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GroupeMediaco\",\"https:\\\/\\\/x.com\\\/GroupeMediaco\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mediaco\\\/\",\"https:\\\/\\\/www.youtube.com\\\/MediacoLevage\",\"https:\\\/\\\/www.instagram.com\\\/groupemediaco\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Actualit\u00e9s et Vie du Groupe - MEDIACO","description":"Retrouvez toutes les actualit\u00e9s du groupe MEDIACO Levage et suivez nos interventions de levage, manutention, transport et logistique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mediaco-groupe.com\/fr\/actualites-levage\/","og_locale":"fr_FR","og_type":"article","og_title":"Actualit\u00e9s et Vie du Groupe - MEDIACO","og_description":"Retrouvez toutes les actualit\u00e9s du groupe MEDIACO Levage et suivez nos interventions de levage, manutention, transport et logistique.","og_url":"https:\/\/mediaco-groupe.com\/fr\/actualites-levage\/","og_site_name":"Location et vente de nacelles, grues, mat\u00e9riels de levage - Mediaco","article_publisher":"https:\/\/www.facebook.com\/GroupeMediaco","article_modified_time":"2024-10-30T10:30:00+00:00","og_image":[{"url":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/07\/grue-mobile-industriel-1024x683.webp","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@GroupeMediaco","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mediaco-groupe.com\/fr\/actualites-levage\/","url":"https:\/\/mediaco-groupe.com\/fr\/actualites-levage\/","name":"Actualit\u00e9s et Vie du Groupe - MEDIACO","isPartOf":{"@id":"https:\/\/mediaco-groupe.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mediaco-groupe.com\/fr\/actualites-levage\/#primaryimage"},"image":{"@id":"https:\/\/mediaco-groupe.com\/fr\/actualites-levage\/#primaryimage"},"thumbnailUrl":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/07\/grue-mobile-industriel-1024x683.webp","datePublished":"2022-01-11T09:27:47+00:00","dateModified":"2024-10-30T10:30:00+00:00","description":"Retrouvez toutes les actualit\u00e9s du groupe MEDIACO Levage et suivez nos interventions de levage, manutention, transport et logistique.","breadcrumb":{"@id":"https:\/\/mediaco-groupe.com\/fr\/actualites-levage\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mediaco-groupe.com\/fr\/actualites-levage\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mediaco-groupe.com\/fr\/actualites-levage\/#primaryimage","url":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/07\/grue-mobile-industriel-1024x683.webp","contentUrl":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/07\/grue-mobile-industriel-1024x683.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/mediaco-groupe.com\/fr\/actualites-levage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/mediaco-groupe.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Actualit\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/mediaco-groupe.com\/fr\/#website","url":"https:\/\/mediaco-groupe.com\/fr\/","name":"Location et vente de nacelles, grues, mat\u00e9riels de levage - Mediaco","description":"Premier r\u00e9seau en France dans le Levage et la Manutention","publisher":{"@id":"https:\/\/mediaco-groupe.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mediaco-groupe.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mediaco-groupe.com\/fr\/#organization","name":"Mediaco Levage","url":"https:\/\/mediaco-groupe.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mediaco-groupe.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/01\/logo-mediaco.svg","contentUrl":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/01\/logo-mediaco.svg","width":590,"height":72,"caption":"Mediaco Levage"},"image":{"@id":"https:\/\/mediaco-groupe.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GroupeMediaco","https:\/\/x.com\/GroupeMediaco","https:\/\/www.linkedin.com\/company\/mediaco\/","https:\/\/www.youtube.com\/MediacoLevage","https:\/\/www.instagram.com\/groupemediaco\/"]}]}},"_links":{"self":[{"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/pages\/15","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/comments?post=15"}],"version-history":[{"count":4,"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/pages\/15\/revisions"}],"predecessor-version":[{"id":668291,"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/pages\/15\/revisions\/668291"}],"wp:attachment":[{"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/media?parent=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}