{"id":540486,"date":"2024-05-31T09:12:54","date_gmt":"2024-05-31T07:12:54","guid":{"rendered":"https:\/\/mediaco-groupe.com\/?p=540486"},"modified":"2024-06-10T15:14:30","modified_gmt":"2024-06-10T13:14:30","slug":"inauguration-agence-mediaco-loire","status":"publish","type":"post","link":"https:\/\/mediaco-groupe.com\/fr\/inauguration-agence-mediaco-loire\/","title":{"rendered":"Inauguration de la nouvelle agence MEDIACO LOIRE"},"content":{"rendered":"<p>Plus de <strong>200 personnes<\/strong> (Clients, fournisseurs, amis et partenaires) ont \u00e9t\u00e9 invit\u00e9es ce vendredi 31 mai pour c\u00e9l\u00e9brer les 30 ans de notre agence <strong>MEDIACO LOIRE<\/strong> ainsi que l\u2019inauguration de nos nouvelles installations \u00e0 Andr\u00e9zieux-Bouth\u00e9on, pr\u00e8s de Saint-\u00c9tienne.<\/p>\n<p>Nos \u00e9quipes ont chaleureusement accueilli leurs h\u00f4tes sur ce nouveau site, o\u00f9 \u00e9taient expos\u00e9s nos mat\u00e9riels dont la toute derni\u00e8re acquisition de l\u2019agence : la remorque modulaire SPMT de marque Cometto. Cette derni\u00e8re marque le lancement de notre nouvelle activit\u00e9 de transport en Loire avec la division <strong>HEAVYLIFT<\/strong>, sp\u00e9cialis\u00e9e dans le transfert industriel et la manutention lourde, qui dispose de <strong>100 lignes SPMT<\/strong> et est pr\u00e9sente \u00e0 Lyon et \u00e0 Saint-\u00c9tienne.<\/p>\n<p>Aujourd\u2019hui, MEDIACO LOIRE dispose de 8 grues mobiles, 10 camions bras, des plateformes, tortues et autres accessoires de manutention. Elle fait partie de notre r\u00e9gion RH\u00d4NE-ALPES \/ SAVOIE, qui dispose d\u2019un parc de 180 grues r\u00e9parties \u00e0 travers 11 agences.<\/p>\n<p>Merci \u00e0 tous d\u2019avoir particip\u00e9 \u00e0 cet \u00e9v\u00e9nement et n\u2019h\u00e9sitez pas \u00e0 nous contacter pour vos besoins en levage, manutention et transport.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-540493\" src=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-1-300x200.webp\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-1-300x200.webp 300w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-1-1024x683.webp 1024w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-1-768x512.webp 768w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-1-1536x1024.webp 1536w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-1-18x12.webp 18w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-1.webp 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"alignnone size-medium wp-image-540494\" src=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-2-300x200.webp\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-2-300x200.webp 300w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-2-1024x683.webp 1024w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-2-768x512.webp 768w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-2-1536x1024.webp 1536w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-2-18x12.webp 18w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-2.webp 1843w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"alignnone size-medium wp-image-540495\" src=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-3-300x200.webp\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-3-300x200.webp 300w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-3-1024x683.webp 1024w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-3-768x512.webp 768w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-3-1536x1024.webp 1536w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-3-18x12.webp 18w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-3.webp 1843w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-540496\" src=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-4-300x200.webp\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-4-300x200.webp 300w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-4-1024x683.webp 1024w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-4-768x512.webp 768w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-4-1536x1024.webp 1536w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-4-18x12.webp 18w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-4.webp 1843w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-540497\" src=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-5-300x200.webp\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-5-300x200.webp 300w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-5-1024x683.webp 1024w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-5-768x512.webp 768w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-5-1536x1024.webp 1536w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-5-18x12.webp 18w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-5.webp 1843w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-540498\" src=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-6-300x200.webp\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-6-300x200.webp 300w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-6-1024x683.webp 1024w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-6-768x512.webp 768w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-6-1536x1024.webp 1536w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-6-18x12.webp 18w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-6.webp 1843w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-540499\" src=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-7-300x200.webp\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-7-300x200.webp 300w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-7-1024x683.webp 1024w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-7-768x512.webp 768w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-7-1536x1024.webp 1536w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-7-18x12.webp 18w, https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire-7.webp 1843w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Plus de 200 personnes (Clients, fournisseurs, amis et partenaires) ont \u00e9t\u00e9 invit\u00e9es ce vendredi 31 mai pour c\u00e9l\u00e9brer les 30 ans de notre agence MEDIACO LOIRE ainsi que l\u2019inauguration de nos nouvelles installations \u00e0 Andr\u00e9zieux-Bouth\u00e9on, pr\u00e8s de Saint-\u00c9tienne. Nos \u00e9quipes ont chaleureusement accueilli leurs h\u00f4tes sur ce nouveau site, o\u00f9 \u00e9taient expos\u00e9s nos mat\u00e9riels dont [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":540489,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-540486","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evenement"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inauguration de la nouvelle agence MEDIACO LOIRE<\/title>\n<meta name=\"description\" content=\"Le Groupe Mediaco annonce la cr\u00e9ation d&#039;une nouvelle activit\u00e9 de transport avec 50 lignes de remorques SPMT aux couleurs Mediaco.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mediaco-groupe.com\/fr\/inauguration-agence-mediaco-loire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inauguration de la nouvelle agence MEDIACO LOIRE\" \/>\n<meta property=\"og:description\" content=\"Le Groupe Mediaco annonce la cr\u00e9ation d&#039;une nouvelle activit\u00e9 de transport avec 50 lignes de remorques SPMT aux couleurs Mediaco.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mediaco-groupe.com\/fr\/inauguration-agence-mediaco-loire\/\" \/>\n<meta property=\"og:site_name\" content=\"Location et vente de nacelles, grues, mat\u00e9riels de levage - Mediaco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GroupeMediaco\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-31T07:12:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-10T13:14:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1843\" \/>\n\t<meta property=\"og:image:height\" content=\"1229\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"admin_info\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GroupeMediaco\" \/>\n<meta name=\"twitter:site\" content=\"@GroupeMediaco\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_info\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/inauguration-agence-mediaco-loire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/inauguration-agence-mediaco-loire\\\/\"},\"author\":{\"name\":\"admin_info\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#\\\/schema\\\/person\\\/43f83957359dd6df3b9842372037dbf0\"},\"headline\":\"Inauguration de la nouvelle agence MEDIACO LOIRE\",\"datePublished\":\"2024-05-31T07:12:54+00:00\",\"dateModified\":\"2024-06-10T13:14:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/inauguration-agence-mediaco-loire\\\/\"},\"wordCount\":188,\"publisher\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/inauguration-agence-mediaco-loire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mediaco-groupe.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/inauguration-agence-mediaco-loire.webp\",\"articleSection\":[\"\u00c9v\u00e8nement\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/inauguration-agence-mediaco-loire\\\/\",\"url\":\"https:\\\/\\\/mediaco-groupe.com\\\/inauguration-agence-mediaco-loire\\\/\",\"name\":\"Inauguration de la nouvelle agence MEDIACO LOIRE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/inauguration-agence-mediaco-loire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/inauguration-agence-mediaco-loire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mediaco-groupe.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/inauguration-agence-mediaco-loire.webp\",\"datePublished\":\"2024-05-31T07:12:54+00:00\",\"dateModified\":\"2024-06-10T13:14:30+00:00\",\"description\":\"Le Groupe Mediaco annonce la cr\u00e9ation d'une nouvelle activit\u00e9 de transport avec 50 lignes de remorques SPMT aux couleurs Mediaco.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/inauguration-agence-mediaco-loire\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mediaco-groupe.com\\\/inauguration-agence-mediaco-loire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/inauguration-agence-mediaco-loire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mediaco-groupe.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/inauguration-agence-mediaco-loire.webp\",\"contentUrl\":\"https:\\\/\\\/mediaco-groupe.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/inauguration-agence-mediaco-loire.webp\",\"width\":1843,\"height\":1229,\"caption\":\"Inauguration de l'agence Mediaco Loire\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/inauguration-agence-mediaco-loire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inauguration de la nouvelle agence MEDIACO LOIRE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/\",\"name\":\"Location et vente de nacelles, grues, mat\u00e9riels de levage - Mediaco\",\"description\":\"Premier r\u00e9seau en France dans le Levage et la Manutention\",\"publisher\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#organization\",\"name\":\"Mediaco Levage\",\"url\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mediaco-groupe.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-mediaco.svg\",\"contentUrl\":\"https:\\\/\\\/mediaco-groupe.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-mediaco.svg\",\"width\":590,\"height\":72,\"caption\":\"Mediaco Levage\"},\"image\":{\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GroupeMediaco\",\"https:\\\/\\\/x.com\\\/GroupeMediaco\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mediaco\\\/\",\"https:\\\/\\\/www.youtube.com\\\/MediacoLevage\",\"https:\\\/\\\/www.instagram.com\\\/groupemediaco\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\\\/#\\\/schema\\\/person\\\/43f83957359dd6df3b9842372037dbf0\",\"name\":\"admin_info\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a3a5b368a686f44fa7426827d3de97189099bafe49f9327b727ef912ded8f690?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a3a5b368a686f44fa7426827d3de97189099bafe49f9327b727ef912ded8f690?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a3a5b368a686f44fa7426827d3de97189099bafe49f9327b727ef912ded8f690?s=96&d=mm&r=g\",\"caption\":\"admin_info\"},\"sameAs\":[\"http:\\\/\\\/vps-565ece63.vps.ovh.net\"],\"url\":\"https:\\\/\\\/mediaco-groupe.com\\\/fr\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inauguration de la nouvelle agence MEDIACO LOIRE","description":"Le Groupe Mediaco annonce la cr\u00e9ation d'une nouvelle activit\u00e9 de transport avec 50 lignes de remorques SPMT aux couleurs Mediaco.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mediaco-groupe.com\/fr\/inauguration-agence-mediaco-loire\/","og_locale":"fr_FR","og_type":"article","og_title":"Inauguration de la nouvelle agence MEDIACO LOIRE","og_description":"Le Groupe Mediaco annonce la cr\u00e9ation d'une nouvelle activit\u00e9 de transport avec 50 lignes de remorques SPMT aux couleurs Mediaco.","og_url":"https:\/\/mediaco-groupe.com\/fr\/inauguration-agence-mediaco-loire\/","og_site_name":"Location et vente de nacelles, grues, mat\u00e9riels de levage - Mediaco","article_publisher":"https:\/\/www.facebook.com\/GroupeMediaco","article_published_time":"2024-05-31T07:12:54+00:00","article_modified_time":"2024-06-10T13:14:30+00:00","og_image":[{"width":1843,"height":1229,"url":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire.webp","type":"image\/webp"}],"author":"admin_info","twitter_card":"summary_large_image","twitter_creator":"@GroupeMediaco","twitter_site":"@GroupeMediaco","twitter_misc":{"\u00c9crit par":"admin_info","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mediaco-groupe.com\/inauguration-agence-mediaco-loire\/#article","isPartOf":{"@id":"https:\/\/mediaco-groupe.com\/inauguration-agence-mediaco-loire\/"},"author":{"name":"admin_info","@id":"https:\/\/mediaco-groupe.com\/fr\/#\/schema\/person\/43f83957359dd6df3b9842372037dbf0"},"headline":"Inauguration de la nouvelle agence MEDIACO LOIRE","datePublished":"2024-05-31T07:12:54+00:00","dateModified":"2024-06-10T13:14:30+00:00","mainEntityOfPage":{"@id":"https:\/\/mediaco-groupe.com\/inauguration-agence-mediaco-loire\/"},"wordCount":188,"publisher":{"@id":"https:\/\/mediaco-groupe.com\/fr\/#organization"},"image":{"@id":"https:\/\/mediaco-groupe.com\/inauguration-agence-mediaco-loire\/#primaryimage"},"thumbnailUrl":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire.webp","articleSection":["\u00c9v\u00e8nement"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/mediaco-groupe.com\/inauguration-agence-mediaco-loire\/","url":"https:\/\/mediaco-groupe.com\/inauguration-agence-mediaco-loire\/","name":"Inauguration de la nouvelle agence MEDIACO LOIRE","isPartOf":{"@id":"https:\/\/mediaco-groupe.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mediaco-groupe.com\/inauguration-agence-mediaco-loire\/#primaryimage"},"image":{"@id":"https:\/\/mediaco-groupe.com\/inauguration-agence-mediaco-loire\/#primaryimage"},"thumbnailUrl":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire.webp","datePublished":"2024-05-31T07:12:54+00:00","dateModified":"2024-06-10T13:14:30+00:00","description":"Le Groupe Mediaco annonce la cr\u00e9ation d'une nouvelle activit\u00e9 de transport avec 50 lignes de remorques SPMT aux couleurs Mediaco.","breadcrumb":{"@id":"https:\/\/mediaco-groupe.com\/inauguration-agence-mediaco-loire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mediaco-groupe.com\/inauguration-agence-mediaco-loire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mediaco-groupe.com\/inauguration-agence-mediaco-loire\/#primaryimage","url":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire.webp","contentUrl":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2024\/06\/inauguration-agence-mediaco-loire.webp","width":1843,"height":1229,"caption":"Inauguration de l'agence Mediaco Loire"},{"@type":"BreadcrumbList","@id":"https:\/\/mediaco-groupe.com\/inauguration-agence-mediaco-loire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/mediaco-groupe.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Inauguration de la nouvelle agence MEDIACO LOIRE"}]},{"@type":"WebSite","@id":"https:\/\/mediaco-groupe.com\/fr\/#website","url":"https:\/\/mediaco-groupe.com\/fr\/","name":"Location et vente de nacelles, grues, mat\u00e9riels de levage - Mediaco","description":"Premier r\u00e9seau en France dans le Levage et la Manutention","publisher":{"@id":"https:\/\/mediaco-groupe.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mediaco-groupe.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mediaco-groupe.com\/fr\/#organization","name":"Mediaco Levage","url":"https:\/\/mediaco-groupe.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mediaco-groupe.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/01\/logo-mediaco.svg","contentUrl":"https:\/\/mediaco-groupe.com\/wp-content\/uploads\/2022\/01\/logo-mediaco.svg","width":590,"height":72,"caption":"Mediaco Levage"},"image":{"@id":"https:\/\/mediaco-groupe.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GroupeMediaco","https:\/\/x.com\/GroupeMediaco","https:\/\/www.linkedin.com\/company\/mediaco\/","https:\/\/www.youtube.com\/MediacoLevage","https:\/\/www.instagram.com\/groupemediaco\/"]},{"@type":"Person","@id":"https:\/\/mediaco-groupe.com\/fr\/#\/schema\/person\/43f83957359dd6df3b9842372037dbf0","name":"admin_info","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a3a5b368a686f44fa7426827d3de97189099bafe49f9327b727ef912ded8f690?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a3a5b368a686f44fa7426827d3de97189099bafe49f9327b727ef912ded8f690?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a3a5b368a686f44fa7426827d3de97189099bafe49f9327b727ef912ded8f690?s=96&d=mm&r=g","caption":"admin_info"},"sameAs":["http:\/\/vps-565ece63.vps.ovh.net"],"url":"https:\/\/mediaco-groupe.com\/fr"}]}},"_links":{"self":[{"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/posts\/540486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/comments?post=540486"}],"version-history":[{"count":2,"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/posts\/540486\/revisions"}],"predecessor-version":[{"id":540502,"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/posts\/540486\/revisions\/540502"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/media\/540489"}],"wp:attachment":[{"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/media?parent=540486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/categories?post=540486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mediaco-groupe.com\/fr\/wp-json\/wp\/v2\/tags?post=540486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}